{"id":1410,"date":"2011-02-27T11:29:36","date_gmt":"2011-02-27T10:29:36","guid":{"rendered":"https:\/\/artcrash.com\/de\/?p=1410"},"modified":"2017-04-26T11:30:31","modified_gmt":"2017-04-26T09:30:31","slug":"know-how-fuer-die-energiewirtschaft-auf-der-e-world-energy-water","status":"publish","type":"post","link":"https:\/\/artcrash.com\/de\/know-how-fuer-die-energiewirtschaft-auf-der-e-world-energy-water\/","title":{"rendered":"Know-how f\u00fcr die Energiewirtschaft auf der E-World Energy &#038; Water"},"content":{"rendered":"<p>arvato infoscore ist eine Tochter der arvato AG, des international vernetzten Medien- und Kommunikationsdienstleisters der Bertelsmann AG. Die Unternehmensgruppe mit rund 1.500 Mitarbeitern und Hauptsitz in Baden-Baden ist in Deutschland, \u00d6sterreich, der Schweiz und Ungarn t\u00e4tig.<\/p>\n<p>arvato inforscore mit seinen integrierten Dienstleistungen f\u00fcr die Energiewirtschaft pr\u00e4sentierte sich auf der E-World Energy &#038; Water mit Diskussionsrunden \u00fcber die Potenziale im Services-Bereich entlang der Wertsch\u00f6pfungskette. Informationen \u00fcber das umfassende Dienstleistungsangebot zu den Themen Kundenbetreuung und -entwicklung, Neukundengewinnung, IT-Solutions, Financial- und Outsourcing-Services wurden bereitgestellt.<\/p>\n<p>Art Crash konzipierte den publikumswirksamen Messestand, messebegleitende Werbung und als Aktion einen &#8222;arvato-Schrittz\u00e4hler&#8220; unter dem Motto &#8222;Gehen Sie effiziente Wege&#8220;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>arvato infoscore ist eine Tochter der arvato AG, des international vernetzten Medien- und Kommunikationsdienstleisters der Bertelsmann AG. Die Unternehmensgruppe mit rund 1.500 Mitarbeitern und Hauptsitz in Baden-Baden ist in Deutschland, &hellip;<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1410","post","type-post","status-publish","format-standard","hentry","category-allgemein","odd"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/artcrash.com\/de\/wp-json\/wp\/v2\/posts\/1410","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/artcrash.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/artcrash.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/artcrash.com\/de\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/artcrash.com\/de\/wp-json\/wp\/v2\/comments?post=1410"}],"version-history":[{"count":2,"href":"https:\/\/artcrash.com\/de\/wp-json\/wp\/v2\/posts\/1410\/revisions"}],"predecessor-version":[{"id":1412,"href":"https:\/\/artcrash.com\/de\/wp-json\/wp\/v2\/posts\/1410\/revisions\/1412"}],"wp:attachment":[{"href":"https:\/\/artcrash.com\/de\/wp-json\/wp\/v2\/media?parent=1410"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/artcrash.com\/de\/wp-json\/wp\/v2\/categories?post=1410"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/artcrash.com\/de\/wp-json\/wp\/v2\/tags?post=1410"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}