{"id":3103,"date":"2022-12-06T16:19:38","date_gmt":"2022-12-06T15:19:38","guid":{"rendered":"https:\/\/artcrash.com\/de\/?p=3103"},"modified":"2022-12-07T16:39:01","modified_gmt":"2022-12-07T15:39:01","slug":"unternehmenspraesentation-als-interaktive-app","status":"publish","type":"post","link":"https:\/\/artcrash.com\/de\/unternehmenspraesentation-als-interaktive-app\/","title":{"rendered":"Unternehmenspr\u00e4sentation als interaktive App"},"content":{"rendered":"<p>F\u00fcr die ROB Group hat Art Crash eine interaktive zweisprachige App entwickelt, in der die unterschiedlichen Dienstleistungen und Services des Unternehmens dargestellt werden. Das Interface-Design ist \u00fcbersichtlich und klar strukturiert. So kann sich der User auf die Inhalte fokussieren, die wichtigsten Infos und Beispiele aus den Bereichen Elektronikentwicklung, Elektronikfertigung, Kabelkonfektionierung sowie Logistik abrufen und einen \u00dcberblick \u00fcber die vielf\u00e4ltigen Elektronik-Dienstleistungen von ROB erhalten.<\/p>\n<p>Sie suchen auch nach einer multifunktionalen L\u00f6sung, um Ihr Unternehmen offline wie online auf innovative und intuitive Weise zu pr\u00e4sentieren? Dann ist Art Crash der richtige Partner f\u00fcr Sie.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>F\u00fcr die ROB Group hat Art Crash eine interaktive zweisprachige App entwickelt, in der die unterschiedlichen Dienstleistungen und Services des Unternehmens dargestellt werden.<\/p>\n","protected":false},"author":4,"featured_media":3104,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[1],"tags":[19],"class_list":["post-3103","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","tag-startseitenbeitrag","odd"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/artcrash.com\/de\/wp-json\/wp\/v2\/posts\/3103","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/artcrash.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/artcrash.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/artcrash.com\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/artcrash.com\/de\/wp-json\/wp\/v2\/comments?post=3103"}],"version-history":[{"count":5,"href":"https:\/\/artcrash.com\/de\/wp-json\/wp\/v2\/posts\/3103\/revisions"}],"predecessor-version":[{"id":3109,"href":"https:\/\/artcrash.com\/de\/wp-json\/wp\/v2\/posts\/3103\/revisions\/3109"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/artcrash.com\/de\/wp-json\/wp\/v2\/media\/3104"}],"wp:attachment":[{"href":"https:\/\/artcrash.com\/de\/wp-json\/wp\/v2\/media?parent=3103"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/artcrash.com\/de\/wp-json\/wp\/v2\/categories?post=3103"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/artcrash.com\/de\/wp-json\/wp\/v2\/tags?post=3103"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}